{"id":2609,"date":"2022-10-05T12:35:14","date_gmt":"2022-10-05T12:35:14","guid":{"rendered":"https:\/\/masergrup.com\/certificado-plant-based\/"},"modified":"2022-11-17T12:48:08","modified_gmt":"2022-11-17T12:48:08","slug":"certificacio-plant-based","status":"publish","type":"post","link":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/","title":{"rendered":"CERTIFICACI\u00d3 PLANT BASED"},"content":{"rendered":"<p>Cada vegada m\u00e9s els consumidors prefereixen un consum m\u00e9s basat en vegetals i les opcions existents en el mercat poden portar-nos a confusi\u00f3 a causa de les innovacions.<\/p>\n<p>Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de <a href=\"https:\/\/www.nsf.org\/testing\/food\/food-beverage-product-certification\/plant-based-certification\"><strong>productes basats en plantes<\/strong><\/a> desapareix, assegurant-nos la proced\u00e8ncia vegetal.<\/p>\n<p>El certificat\u00a0Plant\u00a0Based\u00a0no sols diferencia els nostres productes donant-los un segell de qualitat que representa la confian\u00e7a dels nostres clients davant la proced\u00e8ncia dels nostres productes, tamb\u00e9 representa el nostre comprom\u00eds amb el medi ambient i el territori.<\/p>\n<p>Els consumidors que trien productes amb aquest certificat, estan triant alternatives sostenibles i assegurant-se que els seus aliments no tenen traces animals.<\/p>\n<p>A <a href=\"https:\/\/masergrup.com\/ca\/cool_timeline\/go-fruselva-s-l-u\/\"><strong>Global\u00a0Fruselva\u00a0<\/strong><\/a>ens sentim orgullosos de poder comptar amb aquest certificat entre els nostres segells de qualitat i est\u00e0ndards internacionals, ja que representa el nostre comprom\u00eds amb el medi ambient amb el qual la nostra empresa s&#8217;ha comprom\u00e8s a aconseguir totes les metes de desenvolupament sostenible que ha proposat les Nacions Unides.<\/p>\n<p>Com una empresa global,\u00a0Fruselva\u00a0cuida totes les baules de la Cadena de Valor per a controlar l&#8217;impacte social i mediambiental de les seves operacions.<\/p>\n<p>&nbsp;<\/p>\n<span class=\"collapseomatic \" id=\"id6a98a44277f56\"  tabindex=\"0\" title=\"\"    ><\/span><div id=\"target-id6a98a44277f56\" class=\"collapseomatic_content \">\n<p>CERTIFICACI\u00d3 PLANT BASED<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cada vegada m\u00e9s els consumidors prefereixen un consum m\u00e9s basat en vegetals i les opcions existents en el mercat poden portar-nos a confusi\u00f3 a causa de les innovacions. Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal. El certificat\u00a0Plant\u00a0Based\u00a0no sols diferencia els nostres productes donant-los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[41,29],"tags":[],"class_list":["post-2609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fruselva-ca","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CERTIFICACI\u00d3 PLANT BASED - MASERGRUP<\/title>\n<meta name=\"description\" content=\"Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CERTIFICACI\u00d3 PLANT BASED - MASERGRUP\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\" \/>\n<meta property=\"og:site_name\" content=\"MASERGRUP\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T12:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-17T12:48:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"masergrup\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"masergrup\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\"},\"author\":{\"name\":\"masergrup\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3\"},\"headline\":\"CERTIFICACI\u00d3 PLANT BASED\",\"datePublished\":\"2022-10-05T12:35:14+00:00\",\"dateModified\":\"2022-11-17T12:48:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\"},\"wordCount\":207,\"publisher\":{\"@id\":\"https:\/\/masergrup.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg\",\"articleSection\":[\"Fruselva-ca\",\"Noticies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\",\"url\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\",\"name\":\"CERTIFICACI\u00d3 PLANT BASED - MASERGRUP\",\"isPartOf\":{\"@id\":\"https:\/\/masergrup.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg\",\"datePublished\":\"2022-10-05T12:35:14+00:00\",\"dateModified\":\"2022-11-17T12:48:08+00:00\",\"description\":\"Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal\",\"breadcrumb\":{\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage\",\"url\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg\",\"contentUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg\",\"width\":1000,\"height\":624,\"caption\":\"certificaci\u00f3 PLANT BASED\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/masergrup.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CERTIFICACI\u00d3 PLANT BASED\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/masergrup.com\/#website\",\"url\":\"https:\/\/masergrup.com\/\",\"name\":\"MASERGRUP\",\"description\":\"MASERGRUP |  Pasi\u00f3n por la industria, la sostenibilidad, la innovaci\u00f3n, el medioambiente y las personas |\",\"publisher\":{\"@id\":\"https:\/\/masergrup.com\/#organization\"},\"alternateName\":\"Grup industrial Masergrup\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/masergrup.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/masergrup.com\/#organization\",\"name\":\"MASERGRUP\",\"url\":\"https:\/\/masergrup.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png\",\"contentUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png\",\"width\":318,\"height\":192,\"caption\":\"MASERGRUP\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es.linkedin.com\/company\/serveis-i-administracions-masergrup-sl\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3\",\"name\":\"masergrup\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"caption\":\"masergrup\"},\"sameAs\":[\"https:\/\/masergrup.com\"],\"url\":\"https:\/\/masergrup.com\/ca\/author\/masergrup\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CERTIFICACI\u00d3 PLANT BASED - MASERGRUP","description":"Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/","og_locale":"ca_ES","og_type":"article","og_title":"CERTIFICACI\u00d3 PLANT BASED - MASERGRUP","og_description":"Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal","og_url":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/","og_site_name":"MASERGRUP","article_published_time":"2022-10-05T12:35:14+00:00","article_modified_time":"2022-11-17T12:48:08+00:00","og_image":[{"width":1000,"height":624,"url":"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg","type":"image\/jpeg"}],"author":"masergrup","twitter_misc":{"Escrit per":"masergrup","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#article","isPartOf":{"@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/"},"author":{"name":"masergrup","@id":"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3"},"headline":"CERTIFICACI\u00d3 PLANT BASED","datePublished":"2022-10-05T12:35:14+00:00","dateModified":"2022-11-17T12:48:08+00:00","mainEntityOfPage":{"@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/"},"wordCount":207,"publisher":{"@id":"https:\/\/masergrup.com\/#organization"},"image":{"@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage"},"thumbnailUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg","articleSection":["Fruselva-ca","Noticies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/","url":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/","name":"CERTIFICACI\u00d3 PLANT BASED - MASERGRUP","isPartOf":{"@id":"https:\/\/masergrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage"},"image":{"@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage"},"thumbnailUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg","datePublished":"2022-10-05T12:35:14+00:00","dateModified":"2022-11-17T12:48:08+00:00","description":"Gr\u00e0cies a la certificaci\u00f3 Plant Based la confusi\u00f3 davant de productes basats en plantes desapareix, assegurant-nos la proced\u00e8ncia vegetal","breadcrumb":{"@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masergrup.com\/ca\/certificacio-plant-based\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#primaryimage","url":"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg","contentUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2022\/11\/Noti-1.-Certificacion-Plant-Based.jpeg","width":1000,"height":624,"caption":"certificaci\u00f3 PLANT BASED"},{"@type":"BreadcrumbList","@id":"https:\/\/masergrup.com\/ca\/certificacio-plant-based\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/masergrup.com\/"},{"@type":"ListItem","position":2,"name":"CERTIFICACI\u00d3 PLANT BASED"}]},{"@type":"WebSite","@id":"https:\/\/masergrup.com\/#website","url":"https:\/\/masergrup.com\/","name":"MASERGRUP","description":"MASERGRUP |  Pasi\u00f3n por la industria, la sostenibilidad, la innovaci\u00f3n, el medioambiente y las personas |","publisher":{"@id":"https:\/\/masergrup.com\/#organization"},"alternateName":"Grup industrial Masergrup","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masergrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/masergrup.com\/#organization","name":"MASERGRUP","url":"https:\/\/masergrup.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/#\/schema\/logo\/image\/","url":"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png","contentUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png","width":318,"height":192,"caption":"MASERGRUP"},"image":{"@id":"https:\/\/masergrup.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es.linkedin.com\/company\/serveis-i-administracions-masergrup-sl"]},{"@type":"Person","@id":"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3","name":"masergrup","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","caption":"masergrup"},"sameAs":["https:\/\/masergrup.com"],"url":"https:\/\/masergrup.com\/ca\/author\/masergrup\/"}]}},"_links":{"self":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/2609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/comments?post=2609"}],"version-history":[{"count":2,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/2609\/revisions"}],"predecessor-version":[{"id":2611,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/2609\/revisions\/2611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/media\/2603"}],"wp:attachment":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/media?parent=2609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/categories?post=2609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/tags?post=2609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}