{"id":2958,"date":"2023-06-22T09:41:51","date_gmt":"2023-06-22T09:41:51","guid":{"rendered":"https:\/\/masergrup.com\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/"},"modified":"2023-06-22T09:51:50","modified_gmt":"2023-06-22T09:51:50","slug":"en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico","status":"publish","type":"post","link":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/","title":{"rendered":"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#8217;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic."},"content":{"rendered":"<p>Per tercer any consecutiu, hem presenciat la celebraci\u00f3 d&#8217;un esdeveniment especial conegut com la Nit del Mecenatge, on la participaci\u00f3 de\u00a0<a href=\"https:\/\/masergrup.com\/ca\/cool_timeline\/go-fruselva-s-l-u\/\"><strong>Fruselva<\/strong><\/a>, a trav\u00e9s del nostre distingit president, <strong>Xavier Mart\u00ednez i Serra<\/strong>, ha estat notable.<\/p>\n<p>En aquesta emocionant edici\u00f3,\u00a0Fruselva\u00a0ha atorgat una prestigiosa <strong>beca<\/strong> en el fascinant camp del <strong>coneixement cient\u00edfic, les matem\u00e0tiques i\/o la tecnologia<\/strong>, i l&#8217;afortunat beneficiari ha estat l&#8217;estudiant <strong>Alex Quesada Quesada.<\/strong><\/p>\n<p>La finalitat d&#8217;aquesta beca, que es renova anualment, consisteix a estimular la inventiva, la curiositat i les aptituds dels estudiants de secund\u00e0ria de SEIS en els camps de la ci\u00e8ncia, la tecnologia i les matem\u00e0tiques, amb el prop\u00f2sit de fomentar la creativitat cient\u00edfica i l&#8217;inter\u00e8s en els <a href=\"https:\/\/www.un.org\/sustainabledevelopment\/es\/objetivos-de-desarrollo-sostenible\/\" target=\"_blank\" rel=\"noopener\"><strong>Objectius de Desenvolupament Sostenible 2030<\/strong> <\/a>entre els alumnes durant el pr\u00f2xim per\u00edode acad\u00e8mic.<\/p>\n<p>\u00c9s un motiu de gran satisfacci\u00f3 per a\u00a0<strong>Fruselva<\/strong>\u00a0concedir aquest prestigi\u00f3s guard\u00f3. Creiem fermament en la import\u00e0ncia de l&#8217;educaci\u00f3 en totes les etapes de l&#8217;exist\u00e8ncia, sobretot en la joventut, on s&#8217;han d&#8217;establir bases s\u00f2lides que forgin un futur prometedor.<\/p>\n<p>Felicitacions, Alex Quesada! T&#8217;animem a continuar esfor\u00e7ant-te amb entusiasme i dedicaci\u00f3.<\/p>\n<span class=\"collapseomatic \" id=\"id6a98a4ca13f3c\"  tabindex=\"0\" title=\"\"    ><\/span><div id=\"target-id6a98a4ca13f3c\" class=\"collapseomatic_content \">\n<h3>NIT DEL MECENATGE<\/h3>\n<p>Una vegada m\u00e9s, s&#8217;ha dut a terme l&#8217;esdeveniment ben\u00e8fic conegut com la Nit del Mecenatge, on\u00a0Fruselva\u00a0ha col\u00b7laborat i ha estat representada pel nostre president, Xavier Mart\u00ednez i Serra.<\/p>\n<p>En aquesta edici\u00f3,\u00a0Fruselva\u00a0ha concedit la beca en l&#8217;\u00e0mbit cient\u00edfic, matem\u00e0tic i\/o tecnol\u00f2gic a l&#8217;estudiant Alex Quesada Quesada.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per tercer any consecutiu, hem presenciat la celebraci\u00f3 d&#8217;un esdeveniment especial conegut com la Nit del Mecenatge, on la participaci\u00f3 de\u00a0Fruselva, a trav\u00e9s del nostre distingit president, Xavier Mart\u00ednez i Serra, ha estat notable. En aquesta emocionant edici\u00f3,\u00a0Fruselva\u00a0ha atorgat una prestigiosa beca en el fascinant camp del coneixement cient\u00edfic, les matem\u00e0tiques i\/o la tecnologia, i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[41,29],"tags":[],"class_list":["post-2958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fruselva-ca","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#039;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic. - MASERGRUP<\/title>\n<meta name=\"description\" content=\"Fruselva ha otorgat una prestigiosa beca durante la Nit del Mecenatge de la Socrates Educa International School.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#039;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic. - MASERGRUP\" \/>\n<meta property=\"og:description\" content=\"Fruselva ha otorgat una prestigiosa beca durante la Nit del Mecenatge de la Socrates Educa International School.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\" \/>\n<meta property=\"og:site_name\" content=\"MASERGRUP\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-22T09:41:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-22T09:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"masergrup\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"masergrup\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\"},\"author\":{\"name\":\"masergrup\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3\"},\"headline\":\"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#8217;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic.\",\"datePublished\":\"2023-06-22T09:41:51+00:00\",\"dateModified\":\"2023-06-22T09:51:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\"},\"wordCount\":286,\"publisher\":{\"@id\":\"https:\/\/masergrup.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg\",\"articleSection\":[\"Fruselva-ca\",\"Noticies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\",\"url\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\",\"name\":\"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l'\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic. - MASERGRUP\",\"isPartOf\":{\"@id\":\"https:\/\/masergrup.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg\",\"datePublished\":\"2023-06-22T09:41:51+00:00\",\"dateModified\":\"2023-06-22T09:51:50+00:00\",\"description\":\"Fruselva ha otorgat una prestigiosa beca durante la Nit del Mecenatge de la Socrates Educa International School.\",\"breadcrumb\":{\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage\",\"url\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg\",\"contentUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg\",\"width\":1080,\"height\":675,\"caption\":\"Nit del Mecenatge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/masergrup.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#8217;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/masergrup.com\/#website\",\"url\":\"https:\/\/masergrup.com\/\",\"name\":\"MASERGRUP\",\"description\":\"MASERGRUP |  Pasi\u00f3n por la industria, la sostenibilidad, la innovaci\u00f3n, el medioambiente y las personas |\",\"publisher\":{\"@id\":\"https:\/\/masergrup.com\/#organization\"},\"alternateName\":\"Grup industrial Masergrup\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/masergrup.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/masergrup.com\/#organization\",\"name\":\"MASERGRUP\",\"url\":\"https:\/\/masergrup.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png\",\"contentUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png\",\"width\":318,\"height\":192,\"caption\":\"MASERGRUP\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es.linkedin.com\/company\/serveis-i-administracions-masergrup-sl\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3\",\"name\":\"masergrup\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"caption\":\"masergrup\"},\"sameAs\":[\"https:\/\/masergrup.com\"],\"url\":\"https:\/\/masergrup.com\/ca\/author\/masergrup\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l'\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic. - MASERGRUP","description":"Fruselva ha otorgat una prestigiosa beca durante la Nit del Mecenatge de la Socrates Educa International School.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/","og_locale":"ca_ES","og_type":"article","og_title":"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l'\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic. - MASERGRUP","og_description":"Fruselva ha otorgat una prestigiosa beca durante la Nit del Mecenatge de la Socrates Educa International School.","og_url":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/","og_site_name":"MASERGRUP","article_published_time":"2023-06-22T09:41:51+00:00","article_modified_time":"2023-06-22T09:51:50+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg","type":"image\/jpeg"}],"author":"masergrup","twitter_misc":{"Escrit per":"masergrup","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#article","isPartOf":{"@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/"},"author":{"name":"masergrup","@id":"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3"},"headline":"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#8217;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic.","datePublished":"2023-06-22T09:41:51+00:00","dateModified":"2023-06-22T09:51:50+00:00","mainEntityOfPage":{"@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/"},"wordCount":286,"publisher":{"@id":"https:\/\/masergrup.com\/#organization"},"image":{"@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage"},"thumbnailUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg","articleSection":["Fruselva-ca","Noticies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/","url":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/","name":"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l'\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic. - MASERGRUP","isPartOf":{"@id":"https:\/\/masergrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage"},"image":{"@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage"},"thumbnailUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg","datePublished":"2023-06-22T09:41:51+00:00","dateModified":"2023-06-22T09:51:50+00:00","description":"Fruselva ha otorgat una prestigiosa beca durante la Nit del Mecenatge de la Socrates Educa International School.","breadcrumb":{"@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#primaryimage","url":"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg","contentUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2023\/06\/Fruselva-beca.jpg","width":1080,"height":675,"caption":"Nit del Mecenatge"},{"@type":"BreadcrumbList","@id":"https:\/\/masergrup.com\/ca\/en-la-noche-del-mecenazgo-de-socrates-educa-international-school-fruselva-concedio-la-beca-en-el-ambito-cientifico-matematico-y-o-tecnologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/masergrup.com\/"},{"@type":"ListItem","position":2,"name":"A la Nit del Mecenatge de Socrates Educa International School, Fruselva va concedir la beca en l&#8217;\u00e0mbit Cient\u00edfic, Matem\u00e0tic i\/o Tecnol\u00f2gic."}]},{"@type":"WebSite","@id":"https:\/\/masergrup.com\/#website","url":"https:\/\/masergrup.com\/","name":"MASERGRUP","description":"MASERGRUP |  Pasi\u00f3n por la industria, la sostenibilidad, la innovaci\u00f3n, el medioambiente y las personas |","publisher":{"@id":"https:\/\/masergrup.com\/#organization"},"alternateName":"Grup industrial Masergrup","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masergrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/masergrup.com\/#organization","name":"MASERGRUP","url":"https:\/\/masergrup.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/#\/schema\/logo\/image\/","url":"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png","contentUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png","width":318,"height":192,"caption":"MASERGRUP"},"image":{"@id":"https:\/\/masergrup.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es.linkedin.com\/company\/serveis-i-administracions-masergrup-sl"]},{"@type":"Person","@id":"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3","name":"masergrup","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","caption":"masergrup"},"sameAs":["https:\/\/masergrup.com"],"url":"https:\/\/masergrup.com\/ca\/author\/masergrup\/"}]}},"_links":{"self":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/2958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/comments?post=2958"}],"version-history":[{"count":4,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/2958\/revisions"}],"predecessor-version":[{"id":2964,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/2958\/revisions\/2964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/media\/2954"}],"wp:attachment":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/media?parent=2958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/categories?post=2958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/tags?post=2958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}