{"id":4204,"date":"2025-04-14T13:00:21","date_gmt":"2025-04-14T13:00:21","guid":{"rendered":"https:\/\/masergrup.com\/?p=4204"},"modified":"2025-04-14T13:32:37","modified_gmt":"2025-04-14T13:32:37","slug":"miro-vermouth-tanca-gran-any","status":"publish","type":"post","link":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/","title":{"rendered":"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup"},"content":{"rendered":"<p class=\"\" data-start=\"552\" data-end=\"786\">A <strong>MaserGrup<\/strong> estem d\u2019enhorabona. Una de les nostres marques m\u00e9s emblem\u00e0tiques, <strong>Mir\u00f3 Vermouth<\/strong>, ha viscut un 2024 extraordinari, amb xifres <strong>que confirmen la seva traject\u00f2ria d\u2019\u00e8xit<\/strong> i el comprom\u00eds compartit amb la qualitat i la innovaci\u00f3.<\/p>\n<p class=\"\" data-start=\"788\" data-end=\"1145\"><strong>Amb un total de 6 milions de litres venuts<\/strong> \u2014un 7% m\u00e9s que el 2023\u2014, Mir\u00f3 es mant\u00e9 com a <strong>marca l\u00edder en el sector del vermut a Catalunya<\/strong> i continua consolidant la seva pres\u00e8ncia en el mercat nacional i internacional. La facturaci\u00f3 ha assolit els 10,78 milions d\u2019euros (un 9,6% m\u00e9s que l\u2019any anterior) i l\u2019EBITDA ha crescut un 11%, arribant als 707.000 euros.<\/p>\n<p class=\"\" data-start=\"1147\" data-end=\"1553\">Aquestes xifres reflecteixen <strong>l\u2019esfor\u00e7 conjunt d\u2019un equip comprom\u00e8s<\/strong> i una estrat\u00e8gia que combina tradici\u00f3 amb visi\u00f3 de futur. El 2024 s\u2019ha tancat tamb\u00e9 amb una inversi\u00f3 de 425.000 euros destinada a la millora dels processos productius. <strong>Per al 2025, Mir\u00f3 preveu una inversi\u00f3 de 1,7 milions d\u2019euros<\/strong>, amb l\u2019objectiu d\u2019ampliar la seva capacitat productiva i continuar obrint nous mercats a escala internacional.<\/p>\n<p class=\"\" data-start=\"1555\" data-end=\"1899\"><strong>A MaserGrup<\/strong> ens omple de satisfacci\u00f3 acompanyar Mir\u00f3 Vermouth en aquest cam\u00ed de creixement sostingut. Des de la seva fundaci\u00f3 a Cornudella de Montsant el 1914 i el seu establiment a Reus el 1957, Mir\u00f3 ha sabut mantenir-se fidel als seus valors i adaptar-se als nous temps. Encarem un 2025 amb il\u00b7lusi\u00f3 i confian\u00e7a per seguir sumant \u00e8xits junts.<\/p>\n<span class=\"collapseomatic \" id=\"id6a98a4caf1c25\"  tabindex=\"0\" title=\"\"    ><\/span><div id=\"target-id6a98a4caf1c25\" class=\"collapseomatic_content \">\n<p><img alt=\"mir\u00f3\"><br \/>\n<img alt=\"mir\u00f3\"><\/p>\n<p><a href=\" \"><\/a><br \/>\n<a href=\" \"><\/a><\/p>\n<p>Aquest creixement de Mir\u00f3 Vermouth tamb\u00e9 s\u2019ent\u00e9n gr\u00e0cies a la seva capacitat per connectar amb noves generacions d\u2019amants del vermut, sense perdre l\u2019ess\u00e8ncia de sempre. El seu comprom\u00eds amb la sostenibilitat, l\u2019origen i la qualitat dels ingredients ha esdevingut un valor diferencial en un mercat cada vegada m\u00e9s exigent. L\u2019ampliaci\u00f3 de la gamma de productes, amb noves propostes que mantenen el car\u00e0cter artes\u00e0, ha contribu\u00eft a enfortir el vincle amb el consumidor. A MaserGrup, valorem especialment aquesta evoluci\u00f3 constant que combina arrels i innovaci\u00f3, i que situa Mir\u00f3 com una marca preparada per continuar liderant el futur del vermut.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A MaserGrup estem d\u2019enhorabona. Una de les nostres marques m\u00e9s emblem\u00e0tiques, Mir\u00f3 Vermouth, ha viscut un 2024 extraordinari, amb xifres que confirmen la seva traject\u00f2ria d\u2019\u00e8xit i el comprom\u00eds compartit amb la qualitat i la innovaci\u00f3. Amb un total de 6 milions de litres venuts \u2014un 7% m\u00e9s que el 2023\u2014, Mir\u00f3 es mant\u00e9 com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-4204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-miro-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup - MASERGRUP<\/title>\n<meta name=\"description\" content=\"A MaserGrup celebrem els grans resultats de Mir\u00f3 Vermouth el 2024 i les previsions de creixement de cara al 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup - MASERGRUP\" \/>\n<meta property=\"og:description\" content=\"A MaserGrup celebrem els grans resultats de Mir\u00f3 Vermouth el 2024 i les previsions de creixement de cara al 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\" \/>\n<meta property=\"og:site_name\" content=\"MASERGRUP\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T13:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T13:32:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"masergrup\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"masergrup\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\"},\"author\":{\"name\":\"masergrup\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3\"},\"headline\":\"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup\",\"datePublished\":\"2025-04-14T13:00:21+00:00\",\"dateModified\":\"2025-04-14T13:32:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\/\/masergrup.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg\",\"articleSection\":[\"Mir\u00f3-ca\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\",\"url\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\",\"name\":\"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup - MASERGRUP\",\"isPartOf\":{\"@id\":\"https:\/\/masergrup.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg\",\"datePublished\":\"2025-04-14T13:00:21+00:00\",\"dateModified\":\"2025-04-14T13:32:37+00:00\",\"description\":\"A MaserGrup celebrem els grans resultats de Mir\u00f3 Vermouth el 2024 i les previsions de creixement de cara al 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage\",\"url\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg\",\"contentUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/masergrup.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/masergrup.com\/#website\",\"url\":\"https:\/\/masergrup.com\/\",\"name\":\"MASERGRUP\",\"description\":\"MASERGRUP |  Pasi\u00f3n por la industria, la sostenibilidad, la innovaci\u00f3n, el medioambiente y las personas |\",\"publisher\":{\"@id\":\"https:\/\/masergrup.com\/#organization\"},\"alternateName\":\"Grup industrial Masergrup\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/masergrup.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/masergrup.com\/#organization\",\"name\":\"MASERGRUP\",\"url\":\"https:\/\/masergrup.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png\",\"contentUrl\":\"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png\",\"width\":318,\"height\":192,\"caption\":\"MASERGRUP\"},\"image\":{\"@id\":\"https:\/\/masergrup.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es.linkedin.com\/company\/serveis-i-administracions-masergrup-sl\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3\",\"name\":\"masergrup\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/masergrup.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g\",\"caption\":\"masergrup\"},\"sameAs\":[\"https:\/\/masergrup.com\"],\"url\":\"https:\/\/masergrup.com\/ca\/author\/masergrup\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup - MASERGRUP","description":"A MaserGrup celebrem els grans resultats de Mir\u00f3 Vermouth el 2024 i les previsions de creixement de cara al 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/","og_locale":"ca_ES","og_type":"article","og_title":"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup - MASERGRUP","og_description":"A MaserGrup celebrem els grans resultats de Mir\u00f3 Vermouth el 2024 i les previsions de creixement de cara al 2025.","og_url":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/","og_site_name":"MASERGRUP","article_published_time":"2025-04-14T13:00:21+00:00","article_modified_time":"2025-04-14T13:32:37+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg","type":"image\/jpeg"}],"author":"masergrup","twitter_misc":{"Escrit per":"masergrup","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#article","isPartOf":{"@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/"},"author":{"name":"masergrup","@id":"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3"},"headline":"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup","datePublished":"2025-04-14T13:00:21+00:00","dateModified":"2025-04-14T13:32:37+00:00","mainEntityOfPage":{"@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/"},"wordCount":356,"publisher":{"@id":"https:\/\/masergrup.com\/#organization"},"image":{"@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage"},"thumbnailUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg","articleSection":["Mir\u00f3-ca"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/","url":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/","name":"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup - MASERGRUP","isPartOf":{"@id":"https:\/\/masergrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage"},"image":{"@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage"},"thumbnailUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg","datePublished":"2025-04-14T13:00:21+00:00","dateModified":"2025-04-14T13:32:37+00:00","description":"A MaserGrup celebrem els grans resultats de Mir\u00f3 Vermouth el 2024 i les previsions de creixement de cara al 2025.","breadcrumb":{"@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#primaryimage","url":"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg","contentUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/masergrup.com\/ca\/miro-vermouth-tanca-gran-any\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/masergrup.com\/"},{"@type":"ListItem","position":2,"name":"Mir\u00f3 Vermouth tanca un any d\u2019\u00e8xits sota el paraigua de MaserGrup"}]},{"@type":"WebSite","@id":"https:\/\/masergrup.com\/#website","url":"https:\/\/masergrup.com\/","name":"MASERGRUP","description":"MASERGRUP |  Pasi\u00f3n por la industria, la sostenibilidad, la innovaci\u00f3n, el medioambiente y las personas |","publisher":{"@id":"https:\/\/masergrup.com\/#organization"},"alternateName":"Grup industrial Masergrup","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masergrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/masergrup.com\/#organization","name":"MASERGRUP","url":"https:\/\/masergrup.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/#\/schema\/logo\/image\/","url":"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png","contentUrl":"https:\/\/masergrup.com\/wp-content\/uploads\/2024\/06\/Logo_masergrup.png","width":318,"height":192,"caption":"MASERGRUP"},"image":{"@id":"https:\/\/masergrup.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es.linkedin.com\/company\/serveis-i-administracions-masergrup-sl"]},{"@type":"Person","@id":"https:\/\/masergrup.com\/#\/schema\/person\/057d09b5f555d5cedad34994275a53f3","name":"masergrup","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/masergrup.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/442251953f111b43a4668103c7b7c09aa35690e525473fb0bb9db0681ee9c0c3?s=96&d=mm&r=g","caption":"masergrup"},"sameAs":["https:\/\/masergrup.com"],"url":"https:\/\/masergrup.com\/ca\/author\/masergrup\/"}]}},"_links":{"self":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/4204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/comments?post=4204"}],"version-history":[{"count":4,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/4204\/revisions"}],"predecessor-version":[{"id":4216,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/posts\/4204\/revisions\/4216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/media\/4201"}],"wp:attachment":[{"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/media?parent=4204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/categories?post=4204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/masergrup.com\/ca\/wp-json\/wp\/v2\/tags?post=4204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}